{"id":25331,"date":"2023-02-01T11:39:55","date_gmt":"2023-02-01T10:39:55","guid":{"rendered":"https:\/\/www.buhl.de\/finanzblick\/?p=25331"},"modified":"2023-02-01T11:39:55","modified_gmt":"2023-02-01T10:39:55","slug":"deine-individuelle-kundenkarte","status":"publish","type":"post","link":"https:\/\/www.buhl.de\/finanzblick\/deine-individuelle-kundenkarte\/","title":{"rendered":"Deine individuelle Kundenkarte"},"content":{"rendered":"<p style=\"text-align: justify\">Lange Zeit konntest du in finanzblick aus einer limitierten Anzahl an Kundenkarten deine Karte ausw\u00e4hlen und einrichten. Doch nun sind dir keine Grenzen mehr gesetzt! Denn das neuste Update in finanzblick erm\u00f6glicht dir nun <strong>deine eigene individuelle Kundenkarte<\/strong> zu erstellen. \ud83d\udcb3<br \/>\nMit der neuen Funktion hast du nun unendlich viele M\u00f6glichkeiten die Kundenkarten einzurichten, welche du f\u00fcr dich und deine Finanzen brauchst.<\/p>\n<p style=\"text-align: justify\">[wonderplugin_cond deviceexclude=&#8220;Mobile&#8220;]<img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-25378\" src=\"https:\/\/www.buhl.de\/finanzblick\/wp-content\/uploads\/sites\/46\/2023\/02\/Design-ohne-Titel-8-151x300.webp\" alt=\"\" width=\"210\" height=\"418\" \/><\/p>\n<p style=\"text-align: justify\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-25379\" src=\"https:\/\/www.buhl.de\/finanzblick\/wp-content\/uploads\/sites\/46\/2023\/02\/Design-ohne-Titel-9-151x300.webp\" alt=\"\" width=\"210\" height=\"418\" \/>[\/wonderplugin_cond]\n<p style=\"text-align: justify\">Die Erstellung der eigenen Kundenkarte ist dabei simple und intuitiv. Gehe im Kundenkarten-Reiter in finanzblick auf das 3-Punkte-Men\u00fc und anschlie\u00dfend auf \u201eKarte hinzuf\u00fcgen\u201c. [wonderplugin_cond deviceinclude=&#8220;iPhone,iPod,Android&#8220;]<img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-25378 size-full\" src=\"https:\/\/www.buhl.de\/finanzblick\/wp-content\/uploads\/sites\/46\/2023\/02\/Design-ohne-Titel-8.webp\" alt=\"\" width=\"242\" height=\"482\" \/>[\/wonderplugin_cond]\n<p style=\"text-align: justify\">Um nun eine eigene Kundenkarte zu erstellen scrollst du bis nach unten, wo du ein Plus siehst und deine eigene Karte anlegen kannst. Dort hast du nun die M\u00f6glichkeit den Code deiner Karte per Kamera einzuscannen. Lege anschlie\u00dfend einen Namen f\u00fcr die Kundenkarte fest und dr\u00fccke auf \u201efertig\u201c. Schon hast du deine eigene Karte nach deinen W\u00fcnschen erstellt. [wonderplugin_cond deviceinclude=&#8220;iPhone,iPod,Android&#8220;]<img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-25379 size-full\" src=\"https:\/\/www.buhl.de\/finanzblick\/wp-content\/uploads\/sites\/46\/2023\/02\/Design-ohne-Titel-9.webp\" alt=\"\" width=\"242\" height=\"482\" \/>[\/wonderplugin_cond]\n<p style=\"text-align: justify\">Du hast jederzeit die M\u00f6glichkeit die Karte anzupassen oder noch weitere zu erstellen, so beh\u00e4ltst du immer die volle Kontrolle \u00fcber deine Finanzen.<\/p>\n<p style=\"text-align: justify\">Die Funktion ist ein gro\u00dfer Schritt f\u00fcr deine finanzielle Freiheit, da wir uns endlich von den Einschr\u00e4nkungen der festgelegten Kundenkarten verabschieden und dir helfen dein Finanzleben selbst in die Hand zu nehmen. Probiere <a href=\"https:\/\/www.buhl.de\/mein-buhlkonto\/?buhlparam=1040201\">finanzblick<\/a> jetzt aus und erlebe den Unterschied!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Lange Zeit konntest du in finanzblick aus einer limitierten Anzahl an Kundenkarten deine Karte ausw\u00e4hlen und einrichten. Doch nun sind dir keine Grenzen mehr gesetzt! Denn das neuste Update in finanzblick erm\u00f6glicht dir nun deine eigene individuelle Kundenkarte zu erstellen. \ud83d\udcb3 Mit der neuen Funktion hast du nun unendlich viele M\u00f6glichkeiten die Kundenkarten einzurichten, welche [&hellip;]<\/p>\n","protected":false},"author":27,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[1],"tags":[39,58],"class_list":["post-25331","post","type-post","status-publish","format-standard","hentry","category-allgemein","tag-finanzielle-freiheit","tag-kundenkarte"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Deine individuelle Kundenkarte<\/title>\n<meta name=\"description\" content=\"Das neuste Update in finanzblick erm\u00f6glicht dir nun deine eigene individuelle Kundenkarte zu erstellen.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.buhl.de\/finanzblick\/deine-individuelle-kundenkarte\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Deine individuelle Kundenkarte\" \/>\n<meta property=\"og:description\" content=\"Das neuste Update in finanzblick erm\u00f6glicht dir nun deine eigene individuelle Kundenkarte zu erstellen.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.buhl.de\/finanzblick\/deine-individuelle-kundenkarte\/\" \/>\n<meta property=\"og:site_name\" content=\"Finanzblick\" \/>\n<meta property=\"article:published_time\" content=\"2023-02-01T10:39:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.buhl.de\/finanzblick\/wp-content\/uploads\/sites\/46\/2023\/02\/Design-ohne-Titel-8-151x300.webp\" \/>\n<meta name=\"author\" content=\"Administrator\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Administrator\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.buhl.de\\\/finanzblick\\\/deine-individuelle-kundenkarte\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.buhl.de\\\/finanzblick\\\/deine-individuelle-kundenkarte\\\/\"},\"author\":{\"name\":\"Administrator\",\"@id\":\"https:\\\/\\\/www.buhl.de\\\/finanzblick\\\/#\\\/schema\\\/person\\\/deebd79a7012357e72fd58c674f8f40f\"},\"headline\":\"Deine individuelle Kundenkarte\",\"datePublished\":\"2023-02-01T10:39:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.buhl.de\\\/finanzblick\\\/deine-individuelle-kundenkarte\\\/\"},\"wordCount\":246,\"image\":{\"@id\":\"https:\\\/\\\/www.buhl.de\\\/finanzblick\\\/deine-individuelle-kundenkarte\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.buhl.de\\\/finanzblick\\\/wp-content\\\/uploads\\\/sites\\\/46\\\/2023\\\/02\\\/Design-ohne-Titel-8-151x300.webp\",\"keywords\":[\"finanzielle Freiheit\",\"Kundenkarte\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.buhl.de\\\/finanzblick\\\/deine-individuelle-kundenkarte\\\/\",\"url\":\"https:\\\/\\\/www.buhl.de\\\/finanzblick\\\/deine-individuelle-kundenkarte\\\/\",\"name\":\"Deine individuelle Kundenkarte\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.buhl.de\\\/finanzblick\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.buhl.de\\\/finanzblick\\\/deine-individuelle-kundenkarte\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.buhl.de\\\/finanzblick\\\/deine-individuelle-kundenkarte\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.buhl.de\\\/finanzblick\\\/wp-content\\\/uploads\\\/sites\\\/46\\\/2023\\\/02\\\/Design-ohne-Titel-8-151x300.webp\",\"datePublished\":\"2023-02-01T10:39:55+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.buhl.de\\\/finanzblick\\\/#\\\/schema\\\/person\\\/deebd79a7012357e72fd58c674f8f40f\"},\"description\":\"Das neuste Update in finanzblick erm\u00f6glicht dir nun deine eigene individuelle Kundenkarte zu erstellen.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.buhl.de\\\/finanzblick\\\/deine-individuelle-kundenkarte\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.buhl.de\\\/finanzblick\\\/deine-individuelle-kundenkarte\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.buhl.de\\\/finanzblick\\\/deine-individuelle-kundenkarte\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.buhl.de\\\/finanzblick\\\/wp-content\\\/uploads\\\/sites\\\/46\\\/2023\\\/02\\\/Design-ohne-Titel-8-151x300.webp\",\"contentUrl\":\"https:\\\/\\\/www.buhl.de\\\/finanzblick\\\/wp-content\\\/uploads\\\/sites\\\/46\\\/2023\\\/02\\\/Design-ohne-Titel-8-151x300.webp\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.buhl.de\\\/finanzblick\\\/deine-individuelle-kundenkarte\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.buhl.de\\\/finanzblick\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Deine individuelle Kundenkarte\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.buhl.de\\\/finanzblick\\\/#website\",\"url\":\"https:\\\/\\\/www.buhl.de\\\/finanzblick\\\/\",\"name\":\"Finanzblick\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.buhl.de\\\/finanzblick\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.buhl.de\\\/finanzblick\\\/#\\\/schema\\\/person\\\/deebd79a7012357e72fd58c674f8f40f\",\"name\":\"Administrator\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f5b194f3cbb98f416ca451c47c032e9a2dd4cfae3832a299c8b7848dd0115837?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f5b194f3cbb98f416ca451c47c032e9a2dd4cfae3832a299c8b7848dd0115837?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f5b194f3cbb98f416ca451c47c032e9a2dd4cfae3832a299c8b7848dd0115837?s=96&d=mm&r=g\",\"caption\":\"Administrator\"},\"url\":\"https:\\\/\\\/www.buhl.de\\\/finanzblick\\\/author\\\/administrator\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Deine individuelle Kundenkarte","description":"Das neuste Update in finanzblick erm\u00f6glicht dir nun deine eigene individuelle Kundenkarte zu erstellen.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.buhl.de\/finanzblick\/deine-individuelle-kundenkarte\/","og_locale":"de_DE","og_type":"article","og_title":"Deine individuelle Kundenkarte","og_description":"Das neuste Update in finanzblick erm\u00f6glicht dir nun deine eigene individuelle Kundenkarte zu erstellen.","og_url":"https:\/\/www.buhl.de\/finanzblick\/deine-individuelle-kundenkarte\/","og_site_name":"Finanzblick","article_published_time":"2023-02-01T10:39:55+00:00","og_image":[{"url":"https:\/\/www.buhl.de\/finanzblick\/wp-content\/uploads\/sites\/46\/2023\/02\/Design-ohne-Titel-8-151x300.webp","type":"","width":"","height":""}],"author":"Administrator","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Administrator","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.buhl.de\/finanzblick\/deine-individuelle-kundenkarte\/#article","isPartOf":{"@id":"https:\/\/www.buhl.de\/finanzblick\/deine-individuelle-kundenkarte\/"},"author":{"name":"Administrator","@id":"https:\/\/www.buhl.de\/finanzblick\/#\/schema\/person\/deebd79a7012357e72fd58c674f8f40f"},"headline":"Deine individuelle Kundenkarte","datePublished":"2023-02-01T10:39:55+00:00","mainEntityOfPage":{"@id":"https:\/\/www.buhl.de\/finanzblick\/deine-individuelle-kundenkarte\/"},"wordCount":246,"image":{"@id":"https:\/\/www.buhl.de\/finanzblick\/deine-individuelle-kundenkarte\/#primaryimage"},"thumbnailUrl":"https:\/\/www.buhl.de\/finanzblick\/wp-content\/uploads\/sites\/46\/2023\/02\/Design-ohne-Titel-8-151x300.webp","keywords":["finanzielle Freiheit","Kundenkarte"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/www.buhl.de\/finanzblick\/deine-individuelle-kundenkarte\/","url":"https:\/\/www.buhl.de\/finanzblick\/deine-individuelle-kundenkarte\/","name":"Deine individuelle Kundenkarte","isPartOf":{"@id":"https:\/\/www.buhl.de\/finanzblick\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.buhl.de\/finanzblick\/deine-individuelle-kundenkarte\/#primaryimage"},"image":{"@id":"https:\/\/www.buhl.de\/finanzblick\/deine-individuelle-kundenkarte\/#primaryimage"},"thumbnailUrl":"https:\/\/www.buhl.de\/finanzblick\/wp-content\/uploads\/sites\/46\/2023\/02\/Design-ohne-Titel-8-151x300.webp","datePublished":"2023-02-01T10:39:55+00:00","author":{"@id":"https:\/\/www.buhl.de\/finanzblick\/#\/schema\/person\/deebd79a7012357e72fd58c674f8f40f"},"description":"Das neuste Update in finanzblick erm\u00f6glicht dir nun deine eigene individuelle Kundenkarte zu erstellen.","breadcrumb":{"@id":"https:\/\/www.buhl.de\/finanzblick\/deine-individuelle-kundenkarte\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.buhl.de\/finanzblick\/deine-individuelle-kundenkarte\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.buhl.de\/finanzblick\/deine-individuelle-kundenkarte\/#primaryimage","url":"https:\/\/www.buhl.de\/finanzblick\/wp-content\/uploads\/sites\/46\/2023\/02\/Design-ohne-Titel-8-151x300.webp","contentUrl":"https:\/\/www.buhl.de\/finanzblick\/wp-content\/uploads\/sites\/46\/2023\/02\/Design-ohne-Titel-8-151x300.webp"},{"@type":"BreadcrumbList","@id":"https:\/\/www.buhl.de\/finanzblick\/deine-individuelle-kundenkarte\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.buhl.de\/finanzblick\/"},{"@type":"ListItem","position":2,"name":"Deine individuelle Kundenkarte"}]},{"@type":"WebSite","@id":"https:\/\/www.buhl.de\/finanzblick\/#website","url":"https:\/\/www.buhl.de\/finanzblick\/","name":"Finanzblick","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.buhl.de\/finanzblick\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/www.buhl.de\/finanzblick\/#\/schema\/person\/deebd79a7012357e72fd58c674f8f40f","name":"Administrator","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/f5b194f3cbb98f416ca451c47c032e9a2dd4cfae3832a299c8b7848dd0115837?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f5b194f3cbb98f416ca451c47c032e9a2dd4cfae3832a299c8b7848dd0115837?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f5b194f3cbb98f416ca451c47c032e9a2dd4cfae3832a299c8b7848dd0115837?s=96&d=mm&r=g","caption":"Administrator"},"url":"https:\/\/www.buhl.de\/finanzblick\/author\/administrator\/"}]}},"acf":[],"_links":{"self":[{"href":"https:\/\/www.buhl.de\/finanzblick\/wp-json\/wp\/v2\/posts\/25331","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.buhl.de\/finanzblick\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.buhl.de\/finanzblick\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.buhl.de\/finanzblick\/wp-json\/wp\/v2\/users\/27"}],"replies":[{"embeddable":true,"href":"https:\/\/www.buhl.de\/finanzblick\/wp-json\/wp\/v2\/comments?post=25331"}],"version-history":[{"count":0,"href":"https:\/\/www.buhl.de\/finanzblick\/wp-json\/wp\/v2\/posts\/25331\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.buhl.de\/finanzblick\/wp-json\/wp\/v2\/media?parent=25331"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.buhl.de\/finanzblick\/wp-json\/wp\/v2\/categories?post=25331"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.buhl.de\/finanzblick\/wp-json\/wp\/v2\/tags?post=25331"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}