{"id":4612,"date":"2018-12-05T09:22:34","date_gmt":"2018-12-05T08:22:34","guid":{"rendered":"http:\/\/www.buhl.de\/steuer-web\/?page_id=4612"},"modified":"2026-02-03T14:15:46","modified_gmt":"2026-02-03T13:15:46","slug":"deutsche-bank","status":"publish","type":"page","link":"https:\/\/www.buhl.de\/steuer\/deutsche-bank\/","title":{"rendered":"Deutsche Bank"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":27,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"buhl-steuer\/page-deutsche-bank-2022.php","meta":{"_acf_changed":false,"footnotes":""},"categories":[2844],"tags":[],"class_list":["post-4612","page","type-page","status-publish","hentry","category-nosearch"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Nur f\u00fcr Kunden der Deutschen Bank - steuer:Web Rabatt<\/title>\n<meta name=\"description\" content=\"Nur f\u00fcr Kunden der Deutschen Bank \u2705 WISO Steuer-Software von :buhl mit Rabatt kaufen \ud83d\udc49 Hier Preise ansehen.\" \/>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Deutsche Bank\" \/>\n<meta property=\"og:description\" content=\"Nur f\u00fcr Kunden der Deutschen Bank \u2705 WISO Steuer-Software von :buhl mit Rabatt kaufen \ud83d\udc49 Hier Preise ansehen.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.buhl.de\/steuer\/deutsche-bank\/\" \/>\n<meta property=\"og:site_name\" content=\"WISO Steuer: Nr.1 App f\u00fcr die Steuererkl\u00e4rung\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-03T13:15:46+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.buhl.de\\\/steuer\\\/deutsche-bank\\\/\",\"url\":\"https:\\\/\\\/www.buhl.de\\\/steuer\\\/deutsche-bank\\\/\",\"name\":\"Nur f\u00fcr Kunden der Deutschen Bank - steuer:Web Rabatt\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.buhl.de\\\/steuer\\\/#website\"},\"datePublished\":\"2018-12-05T08:22:34+00:00\",\"dateModified\":\"2026-02-03T13:15:46+00:00\",\"description\":\"Nur f\u00fcr Kunden der Deutschen Bank \u2705 WISO Steuer-Software von :buhl mit Rabatt kaufen \ud83d\udc49 Hier Preise ansehen.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.buhl.de\\\/steuer\\\/deutsche-bank\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.buhl.de\\\/steuer\\\/deutsche-bank\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.buhl.de\\\/steuer\\\/deutsche-bank\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Steuererkl\u00e4rung\",\"item\":\"https:\\\/\\\/www.buhl.de\\\/steuer\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Deutsche Bank\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.buhl.de\\\/steuer\\\/#website\",\"url\":\"https:\\\/\\\/www.buhl.de\\\/steuer\\\/\",\"name\":\"WISO Steuer: Nr. 1 Steuer-App\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.buhl.de\\\/steuer\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.buhl.de\\\/steuer\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.buhl.de\\\/steuer\\\/#organization\",\"name\":\"WISO Steuer | Buhl Data Service GmbH\",\"url\":\"https:\\\/\\\/www.buhl.de\\\/steuer\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.buhl.de\\\/steuer\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.buhl.de\\\/steuer\\\/wp-content\\\/uploads\\\/sites\\\/31\\\/2026\\\/02\\\/logo-wiso-steuer-app.svg\",\"contentUrl\":\"https:\\\/\\\/www.buhl.de\\\/steuer\\\/wp-content\\\/uploads\\\/sites\\\/31\\\/2026\\\/02\\\/logo-wiso-steuer-app.svg\",\"width\":375,\"height\":72,\"caption\":\"WISO Steuer | Buhl Data Service GmbH\"},\"image\":{\"@id\":\"https:\\\/\\\/www.buhl.de\\\/steuer\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Nur f\u00fcr Kunden der Deutschen Bank - steuer:Web Rabatt","description":"Nur f\u00fcr Kunden der Deutschen Bank \u2705 WISO Steuer-Software von :buhl mit Rabatt kaufen \ud83d\udc49 Hier Preise ansehen.","robots":{"index":"noindex","follow":"follow"},"og_locale":"de_DE","og_type":"article","og_title":"Deutsche Bank","og_description":"Nur f\u00fcr Kunden der Deutschen Bank \u2705 WISO Steuer-Software von :buhl mit Rabatt kaufen \ud83d\udc49 Hier Preise ansehen.","og_url":"https:\/\/www.buhl.de\/steuer\/deutsche-bank\/","og_site_name":"WISO Steuer: Nr.1 App f\u00fcr die Steuererkl\u00e4rung","article_modified_time":"2026-02-03T13:15:46+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.buhl.de\/steuer\/deutsche-bank\/","url":"https:\/\/www.buhl.de\/steuer\/deutsche-bank\/","name":"Nur f\u00fcr Kunden der Deutschen Bank - steuer:Web Rabatt","isPartOf":{"@id":"https:\/\/www.buhl.de\/steuer\/#website"},"datePublished":"2018-12-05T08:22:34+00:00","dateModified":"2026-02-03T13:15:46+00:00","description":"Nur f\u00fcr Kunden der Deutschen Bank \u2705 WISO Steuer-Software von :buhl mit Rabatt kaufen \ud83d\udc49 Hier Preise ansehen.","breadcrumb":{"@id":"https:\/\/www.buhl.de\/steuer\/deutsche-bank\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.buhl.de\/steuer\/deutsche-bank\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.buhl.de\/steuer\/deutsche-bank\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Steuererkl\u00e4rung","item":"https:\/\/www.buhl.de\/steuer\/"},{"@type":"ListItem","position":2,"name":"Deutsche Bank"}]},{"@type":"WebSite","@id":"https:\/\/www.buhl.de\/steuer\/#website","url":"https:\/\/www.buhl.de\/steuer\/","name":"WISO Steuer: Nr. 1 Steuer-App","description":"","publisher":{"@id":"https:\/\/www.buhl.de\/steuer\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.buhl.de\/steuer\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.buhl.de\/steuer\/#organization","name":"WISO Steuer | Buhl Data Service GmbH","url":"https:\/\/www.buhl.de\/steuer\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.buhl.de\/steuer\/#\/schema\/logo\/image\/","url":"https:\/\/www.buhl.de\/steuer\/wp-content\/uploads\/sites\/31\/2026\/02\/logo-wiso-steuer-app.svg","contentUrl":"https:\/\/www.buhl.de\/steuer\/wp-content\/uploads\/sites\/31\/2026\/02\/logo-wiso-steuer-app.svg","width":375,"height":72,"caption":"WISO Steuer | Buhl Data Service GmbH"},"image":{"@id":"https:\/\/www.buhl.de\/steuer\/#\/schema\/logo\/image\/"}}]}},"acf":[],"wps_subtitle":"","_links":{"self":[{"href":"https:\/\/www.buhl.de\/steuer\/wp-json\/wp\/v2\/pages\/4612","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.buhl.de\/steuer\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.buhl.de\/steuer\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.buhl.de\/steuer\/wp-json\/wp\/v2\/users\/27"}],"replies":[{"embeddable":true,"href":"https:\/\/www.buhl.de\/steuer\/wp-json\/wp\/v2\/comments?post=4612"}],"version-history":[{"count":1,"href":"https:\/\/www.buhl.de\/steuer\/wp-json\/wp\/v2\/pages\/4612\/revisions"}],"predecessor-version":[{"id":4614,"href":"https:\/\/www.buhl.de\/steuer\/wp-json\/wp\/v2\/pages\/4612\/revisions\/4614"}],"wp:attachment":[{"href":"https:\/\/www.buhl.de\/steuer\/wp-json\/wp\/v2\/media?parent=4612"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.buhl.de\/steuer\/wp-json\/wp\/v2\/categories?post=4612"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.buhl.de\/steuer\/wp-json\/wp\/v2\/tags?post=4612"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}